{"id":10028,"date":"2025-12-12T00:39:28","date_gmt":"2025-12-12T00:39:28","guid":{"rendered":"https:\/\/chocolate-rook-941503.hostingersite.com\/?post_type=productos&#038;p=10028"},"modified":"2025-12-12T00:44:16","modified_gmt":"2025-12-12T00:44:16","slug":"andamios-de-acceso-4","status":"publish","type":"productos","link":"https:\/\/anmopyc.es\/en\/productos\/andamios-de-acceso-4\/","title":{"rendered":"Access scaffolding"},"content":{"rendered":"","protected":false},"featured_media":10029,"template":"","meta":{"_acf_changed":false},"categories":[12,11],"categoria-de-producto":[],"marca":[252],"class_list":["post-10028","productos","type-productos","status-publish","has-post-thumbnail","hentry","category-andamios","category-medios-auxiliares","marca-tendo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Andamios de acceso - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/en\/products\/andamios-de-acceso-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andamios de acceso - Anmopyc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/en\/products\/andamios-de-acceso-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T00:44:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/12\/Andamios-de-acceso.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/\",\"name\":\"Andamios de acceso - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Andamios-de-acceso.webp\",\"datePublished\":\"2025-12-12T00:39:28+00:00\",\"dateModified\":\"2025-12-12T00:44:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Andamios-de-acceso.webp\",\"contentUrl\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Andamios-de-acceso.webp\",\"width\":460,\"height\":448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/productos\\\/andamios-de-acceso-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anmopyc.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tendo\",\"item\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/marca\\\/tendo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Andamios de acceso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#website\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anmopyc.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/anmopyc.red\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Access scaffolding - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/en\/products\/andamios-de-acceso-4\/","og_locale":"en_US","og_type":"article","og_title":"Andamios de acceso - Anmopyc","og_url":"https:\/\/anmopyc.es\/en\/products\/andamios-de-acceso-4\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","article_modified_time":"2025-12-12T00:44:16+00:00","og_image":[{"width":460,"height":448,"url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/12\/Andamios-de-acceso.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/","url":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/","name":"Access scaffolding - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/12\/Andamios-de-acceso.webp","datePublished":"2025-12-12T00:39:28+00:00","dateModified":"2025-12-12T00:44:16+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/12\/Andamios-de-acceso.webp","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/12\/Andamios-de-acceso.webp","width":460,"height":448},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/productos\/andamios-de-acceso-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/"},{"@type":"ListItem","position":2,"name":"Tendo","item":"https:\/\/anmopyc.es\/en\/marca\/tendo\/"},{"@type":"ListItem","position":3,"name":"Andamios de acceso"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/#website","url":"https:\/\/anmopyc.es\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos\/10028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/types\/productos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media\/10029"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media?parent=10028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categories?post=10028"},{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categoria-de-producto?post=10028"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/marca?post=10028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}