{"id":1578,"date":"2025-11-13T21:27:21","date_gmt":"2025-11-13T21:27:21","guid":{"rendered":"https:\/\/chocolate-rook-941503.hostingersite.com\/?post_type=productos&#038;p=1578"},"modified":"2026-07-08T06:31:34","modified_gmt":"2026-07-08T06:31:34","slug":"vibrant-rules","status":"publish","type":"productos","link":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/","title":{"rendered":"Vibrant rules"},"content":{"rendered":"<p>La regla vibrante TORNADO es ideal para compactar y vibrar superficies de hormig\u00f3n en todo tipo de obras, desde peque\u00f1as reformas hasta grandes proyectos de pavimentaci\u00f3n. Su dise\u00f1o ergon\u00f3mico, perfil de alta resistencia y variedad de motores disponibles garantizan un trabajo eficiente, c\u00f3modo y adaptado a cada necesidad.<\/p>","protected":false},"featured_media":18174,"template":"","meta":{"_acf_changed":true},"categories":[98,24],"categoria-de-producto":[],"marca":[61],"class_list":["post-1578","productos","type-productos","status-publish","has-post-thumbnail","hentry","category-equipos-ligeros-para-hormigon","category-maquinaria-ligera-y-auxiliar","marca-enar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reglas vibrantes - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/en\/products\/vibrant-rules\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reglas vibrantes - Anmopyc\" \/>\n<meta property=\"og:description\" content=\"La regla vibrante TORNADO es ideal para compactar y vibrar superficies de hormig\u00f3n en todo tipo de obras, desde peque\u00f1as reformas hasta grandes proyectos de pavimentaci\u00f3n. Su dise\u00f1o ergon\u00f3mico, perfil de alta resistencia y variedad de motores disponibles garantizan un trabajo eficiente, c\u00f3modo y adaptado a cada necesidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/en\/products\/vibrant-rules\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T06:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Regla-vibrante-enar-TORNADO-GH.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/\",\"name\":\"Reglas vibrantes - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Regla-vibrante-enar-TORNADO-GH.webp\",\"datePublished\":\"2025-11-13T21:27:21+00:00\",\"dateModified\":\"2026-07-08T06:31:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Regla-vibrante-enar-TORNADO-GH.webp\",\"contentUrl\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Regla-vibrante-enar-TORNADO-GH.webp\",\"width\":460,\"height\":448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/productos\\\/reglas-vibrantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anmopyc.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enar\",\"item\":\"https:\\\/\\\/anmopyc.es\\\/en\\\/marca\\\/enar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reglas vibrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#website\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anmopyc.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\\\/\\\/anmopyc.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\\\/\\\/anmopyc.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/anmopyc.red\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vibrating rulers - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/en\/products\/vibrant-rules\/","og_locale":"en_US","og_type":"article","og_title":"Reglas vibrantes - Anmopyc","og_description":"La regla vibrante TORNADO es ideal para compactar y vibrar superficies de hormig\u00f3n en todo tipo de obras, desde peque\u00f1as reformas hasta grandes proyectos de pavimentaci\u00f3n. Su dise\u00f1o ergon\u00f3mico, perfil de alta resistencia y variedad de motores disponibles garantizan un trabajo eficiente, c\u00f3modo y adaptado a cada necesidad.","og_url":"https:\/\/anmopyc.es\/en\/products\/vibrant-rules\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","article_modified_time":"2026-07-08T06:31:34+00:00","og_image":[{"width":460,"height":448,"url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Regla-vibrante-enar-TORNADO-GH.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/","url":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/","name":"Vibrating rulers - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Regla-vibrante-enar-TORNADO-GH.webp","datePublished":"2025-11-13T21:27:21+00:00","dateModified":"2026-07-08T06:31:34+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Regla-vibrante-enar-TORNADO-GH.webp","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Regla-vibrante-enar-TORNADO-GH.webp","width":460,"height":448},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/en\/productos\/reglas-vibrantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/"},{"@type":"ListItem","position":2,"name":"Enar","item":"https:\/\/anmopyc.es\/en\/marca\/enar\/"},{"@type":"ListItem","position":3,"name":"Reglas vibrantes"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/#website","url":"https:\/\/anmopyc.es\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos\/1578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/types\/productos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media\/18174"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media?parent=1578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categories?post=1578"},{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categoria-de-producto?post=1578"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/marca?post=1578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}