{"id":2705,"date":"2025-11-24T14:57:12","date_gmt":"2025-11-24T14:57:12","guid":{"rendered":"https:\/\/chocolate-rook-941503.hostingersite.com\/?post_type=productos&#038;p=2705"},"modified":"2025-11-24T14:57:34","modified_gmt":"2025-11-24T14:57:34","slug":"cargadoras-5","status":"publish","type":"productos","link":"https:\/\/anmopyc.es\/en\/productos\/cargadoras-5\/","title":{"rendered":"Loaders"},"content":{"rendered":"","protected":false},"featured_media":2697,"template":"","meta":{"_acf_changed":false},"categories":[22,21],"categoria-de-producto":[],"marca":[155],"class_list":["post-2705","productos","type-productos","status-publish","has-post-thumbnail","hentry","category-movimiento-de-tierras-a-cielo-abierto","category-movimiento-de-tierras-y-transporte","marca-liebherr-iberica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cargadoras - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/en\/products\/cargadoras-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cargadoras - Anmopyc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/en\/products\/cargadoras-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T14:57:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/\",\"url\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/\",\"name\":\"Cargadoras - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg\",\"datePublished\":\"2025-11-24T14:57:12+00:00\",\"dateModified\":\"2025-11-24T14:57:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#primaryimage\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg\",\"width\":500,\"height\":244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/anmopyc.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIEBHERR IBERICA\",\"item\":\"https:\/\/anmopyc.es\/fr\/marca\/liebherr-iberica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cargadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/anmopyc.es\/en\/#website\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/anmopyc.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anmopyc.red\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loaders - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/en\/products\/cargadoras-5\/","og_locale":"en_US","og_type":"article","og_title":"Cargadoras - Anmopyc","og_url":"https:\/\/anmopyc.es\/en\/products\/cargadoras-5\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","article_modified_time":"2025-11-24T14:57:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/","url":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/","name":"Loaders - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg","datePublished":"2025-11-24T14:57:12+00:00","dateModified":"2025-11-24T14:57:34+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/productos\/cargadoras-5\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg","width":500,"height":244},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/productos\/cargadoras-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/en\/"},{"@type":"ListItem","position":2,"name":"LIEBHERR IBERICA","item":"https:\/\/anmopyc.es\/fr\/marca\/liebherr-iberica\/"},{"@type":"ListItem","position":3,"name":"Cargadoras"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/en\/#website","url":"https:\/\/anmopyc.es\/en\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/en\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos\/2705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/types\/productos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media\/2697"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media?parent=2705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categories?post=2705"},{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categoria-de-producto?post=2705"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/marca?post=2705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}