{"id":2923,"date":"2025-11-25T20:20:48","date_gmt":"2025-11-25T20:20:48","guid":{"rendered":"https:\/\/chocolate-rook-941503.hostingersite.com\/?post_type=productos&#038;p=2923"},"modified":"2025-11-25T20:20:48","modified_gmt":"2025-11-25T20:20:48","slug":"plantas-de-hormigon-para-prefabricado-3","status":"publish","type":"productos","link":"https:\/\/anmopyc.es\/en\/productos\/plantas-de-hormigon-para-prefabricado-3\/","title":{"rendered":"Precast concrete batching plants"},"content":{"rendered":"","protected":false},"featured_media":2697,"template":"","meta":{"_acf_changed":false},"categories":[88,83],"categoria-de-producto":[],"marca":[155],"class_list":["post-2923","productos","type-productos","status-publish","has-post-thumbnail","hentry","category-fabricacion-y-transporte-de-hormigon-y-mortero","category-produccion-de-materiales-de-contruccion","marca-liebherr-iberica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plantas de hormig\u00f3n para prefabricado - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/en\/products\/plantas-de-hormigon-para-prefabricado-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantas de hormig\u00f3n para prefabricado - Anmopyc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/en\/products\/plantas-de-hormigon-para-prefabricado-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/\",\"url\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/\",\"name\":\"Plantas de hormig\u00f3n para prefabricado - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg\",\"datePublished\":\"2025-11-25T20:20:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#primaryimage\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg\",\"width\":500,\"height\":244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/anmopyc.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIEBHERR IBERICA\",\"item\":\"https:\/\/anmopyc.es\/fr\/marca\/liebherr-iberica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plantas de hormig\u00f3n para prefabricado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/anmopyc.es\/en\/#website\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/anmopyc.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anmopyc.red\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concrete plants for precast - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/en\/products\/plantas-de-hormigon-para-prefabricado-3\/","og_locale":"en_US","og_type":"article","og_title":"Plantas de hormig\u00f3n para prefabricado - Anmopyc","og_url":"https:\/\/anmopyc.es\/en\/products\/plantas-de-hormigon-para-prefabricado-3\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/","url":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/","name":"Concrete plants for precast - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg","datePublished":"2025-11-25T20:20:48+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/logo-liebherr.svg","width":500,"height":244},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/fr\/productos\/plantas-de-hormigon-para-prefabricado-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/en\/"},{"@type":"ListItem","position":2,"name":"LIEBHERR IBERICA","item":"https:\/\/anmopyc.es\/fr\/marca\/liebherr-iberica\/"},{"@type":"ListItem","position":3,"name":"Plantas de hormig\u00f3n para prefabricado"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/en\/#website","url":"https:\/\/anmopyc.es\/en\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/en\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos\/2923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/types\/productos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media\/2697"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/media?parent=2923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categories?post=2923"},{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/categoria-de-producto?post=2923"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/anmopyc.es\/en\/wp-json\/wp\/v2\/marca?post=2923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}