{"id":17000,"date":"2026-03-24T07:04:15","date_gmt":"2026-03-24T07:04:15","guid":{"rendered":"https:\/\/anmopyc.es\/?p=17000"},"modified":"2026-03-24T07:05:17","modified_gmt":"2026-03-24T07:05:17","slug":"anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad","status":"publish","type":"post","link":"https:\/\/anmopyc.es\/fr\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/","title":{"rendered":"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad"},"content":{"rendered":"<p><strong>Desde ANMOPYC estamos ultimando todos los detalles para la 20\u00aa edici\u00f3n de SMOPYC, que tendr\u00e1 lugar entre los pr\u00f3ximos 15 a 18 de abril en Feria de Zaragoza y que se convertir\u00e1 de nuevo en el punto de encuentro de nuestro sector en una edici\u00f3n que ha generado muchas expectativas y que contar\u00e1 con m\u00e1s del 27% de superficie expositiva que en la edici\u00f3n anterior.<\/strong><\/p>\n\n\n\n<p>ANMOPYC estar\u00e1 presente con un stand destacado en el <strong>pabell\u00f3n 9,<\/strong> bautizado como <strong>Pavillon de l'Innovation <\/strong>para esta edici\u00f3n de la feria, y en la que <strong>plus de 50 entreprises partenaires<\/strong> participar\u00e1n tambi\u00e9n de forma activa como expositoras, distribuidas entre los 9 pabellones y la zona exterior que componen el \u00e1rea de exposici\u00f3n.<\/p>\n\n\n\n<p>Nuestro espacio se ubicar\u00e1 en el <strong>pabell\u00f3n 9 stand 017-025<\/strong>, en el que contaremos con una amplia superficie expositiva centrada en un stand corporativo en el que reuniremos a toda la representaci\u00f3n del sector de la maquinaria de construcci\u00f3n y miner\u00eda.<\/p>\n\n\n\n<p><strong>Zona de presentaciones y ponencias<\/strong><\/p>\n\n\n\n<p>Como actividad destacada, desde <strong>ANMOPYC <\/strong>hemos organizado una <strong>zona de presentaciones y ponencias <\/strong>que estar\u00e1 ubicada en el pabell\u00f3n 9, justo enfrente de nuestro stand corporativo, y en la que en colaboraci\u00f3n con PTEC e ITA hemos programado una serie de sesiones tem\u00e1ticas llamada <strong>\u201cInnovation SMOPYC Talks\u201d<\/strong>, que estar\u00e1n centradas en la digitalizaci\u00f3n y sostenibilidad en maquinaria y equipos para construcci\u00f3n y miner\u00eda, con el objetivo de <strong>dar visibilidad a las principales tendencias tecnol\u00f3gicas del sector<\/strong> as\u00ed como compartir desarrollos, experiencias y casos de aplicaci\u00f3n que est\u00e9n impulsando la transformaci\u00f3n de nuestra industria.<\/p>\n\n\n\n<p>Est\u00e1n previstas 4 sesiones que se desarrollar\u00e1n mediante un bloque inicial de ponencias breves presentadas por empresas del sector y a continuaci\u00f3n una mesa redonda con varios panelistas en las que se debatir\u00e1n los principales retos y oportunidades asociadas a la tem\u00e1tica tratada.<\/p>\n\n\n\n<p>Las sesiones se celebrar\u00e1n en las siguientes fechas y horarios:<\/p>\n\n\n\n<p><strong>Sesi\u00f3n 1 \u2013 Digitalizaci\u00f3n de maquinaria y obra: datos, conectividad y nuevos servicios<\/strong><\/p>\n\n\n\n<p>Fecha: 15 abril<\/p>\n\n\n\n<p>Horario: 10:30 \u2013 12:00 h<\/p>\n\n\n\n<p>Enfoque: La sesi\u00f3n abordar\u00e1 el papel de las tecnolog\u00edas digitales en la transformaci\u00f3n de la maquinaria y los procesos de construcci\u00f3n y miner\u00eda. Se explorar\u00e1n soluciones relacionadas con conectividad de equipos, monitorizaci\u00f3n remota, gesti\u00f3n y an\u00e1lisis de datos, mantenimiento predictivo, gemelos digitales o plataformas de gesti\u00f3n de obra.<\/p>\n\n\n\n<p><strong>Sesi\u00f3n 2 \u2013 Robotizaci\u00f3n y automatizaci\u00f3n en maquinaria de construcci\u00f3n<\/strong><\/p>\n\n\n\n<p>Fecha: 15 abril<\/p>\n\n\n\n<p>Horario: 12:15 \u2013 13:45 h<\/p>\n\n\n\n<p>Enfoque: La sesi\u00f3n estar\u00e1 dedicada a tecnolog\u00edas que permitan avanzar hacia mayores niveles de automatizaci\u00f3n en maquinaria y procesos, incluyendo operaci\u00f3n remota, maquinaria aut\u00f3noma o semiaut\u00f3noma, sistemas avanzados de asistencia al operador o integraci\u00f3n de rob\u00f3tica en entornos de construcci\u00f3n y miner\u00eda.<\/p>\n\n\n\n<p><strong>Sesi\u00f3n 3 \u2013 Nuevas fuentes de energ\u00eda y descarbonizaci\u00f3n de la maquinaria<\/strong><\/p>\n\n\n\n<p>Fecha: 15 abril<\/p>\n\n\n\n<p>Horario: 16:00 \u2013 17:30 h<\/p>\n\n\n\n<p>Enfoque: La sesi\u00f3n analizar\u00e1 soluciones orientadas a la reducci\u00f3n de emisiones en maquinaria m\u00f3vil fuera de carretera, incluyendo electrificaci\u00f3n, hidr\u00f3geno, combustibles alternativos, sistemas h\u00edbridos y otras tecnolog\u00edas energ\u00e9ticas que contribuyan a mejorar la eficiencia y sostenibilidad del sector.<\/p>\n\n\n\n<p><strong>Sesi\u00f3n 4 \u2013 Innovaci\u00f3n tecnol\u00f3gica para la seguridad en maquinaria y obra<\/strong><\/p>\n\n\n\n<p>Fecha: 17 abril<\/p>\n\n\n\n<p>Horario: 11:30 \u2013 13:00 h<\/p>\n\n\n\n<p>Enfoque: Esta sesi\u00f3n se centrar\u00e1 en tecnolog\u00edas orientadas a mejorar la seguridad de operadores y trabajadores, como sistemas de detecci\u00f3n y prevenci\u00f3n de accidentes, visi\u00f3n artificial, asistencia avanzada al operador, protecci\u00f3n de zonas de trabajo o soluciones de seguridad activa y pasiva<\/p>\n\n\n\n<p><strong>Stand Misiones Inversas<\/strong><\/p>\n\n\n\n<p>Junto a nuestro stand principal, dispondremos de un espacio reservado para la realizaci\u00f3n de <strong>misiones inversas<\/strong>, en la que organizaremos por un lado una <strong>misi\u00f3n inversa de prensa internacional<\/strong>&nbsp; a trav\u00e9s de la cual el <strong>mi\u00e9rcoles 15 de abril<\/strong> llevaremos a cabo una <strong>jornada de puertas abiertas<\/strong> donde todos los asistentes tendr\u00e1n la posibilidad de conocer a una serie de editoriales de prensa internacional especializada del sector, procedente de pa\u00edses como <strong>Singapur, India, Reino Unido y Alemania<\/strong> para poder interactuar con sus representantes y poder presentarles su empresa, productos, servicios, novedades, etc.<\/p>\n\n\n\n<p>Y por otro lado, en este mismo espacio vamos a llevar a cabo una <strong>misi\u00f3n inversa de compradores<\/strong>, que contar\u00e1 con la presencia de representantes de empresas procedentes de pa\u00edses como Canad\u00e1, Estados Unidos, Kazajist\u00e1n, Canad\u00e1, Estados Unidos, Italia, Tanzania con el objetivo principal de que conozcan a las empresas y productos espa\u00f1oles de su inter\u00e9s, de cara a establecer nuevas v\u00edas de colaboraci\u00f3n y generar nuevas oportunidades de negocio.<\/p>\n\n\n\n<p><strong>Otras actividades destacadas<\/strong><\/p>\n\n\n\n<p>El jueves 16 de abril llevaremos a cabo una presentaci\u00f3n del <strong>proyecto H2MAC,<\/strong> ante la prensa asistente a la feria. Este proyecto en el que estamos trabajando junto a varias entidades y empresas europeas, tiene como objetivo dise\u00f1ar y fabricar dos m\u00e1quinas el\u00e9ctricas propulsadas por pila de combustible de hidr\u00f3geno (FCEV), concretamente una excavadora y una trituradora, para contribuir a la descarbonizaci\u00f3n de la miner\u00eda y la construcci\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n durante el jueves 16 de abril celebraremos el \u201c<strong>Vino ELEVA<\/strong>\u201d, organizado conjuntamente por las 7 organizaciones miembro de la Alianza ELEVA, que se convertir\u00e1 nuevamente en el punto de encuentro y networking de todo el ecosistema de nuestro sector y al que desde ANMOPYC os invitamos a asistir. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Y por \u00faltimo, el viernes 17 de abril recibiremos en nuestro stand a un destacado grupo de alumnos de 4\u00ba de la ESO procedentes de una visita organizada por Feria de Zaragoza, y les mostraremos un poco m\u00e1s en detalle nuestro sector, sus profesiones y especialidades, as\u00ed como todas las oportunidades formativas y laborales que ofrece.<\/p>\n\n\n\n<p>Como conclusi\u00f3n, desde ANMOPYC esperamos la celebraci\u00f3n de esta cita estrat\u00e9gica en el calendario de eventos del sector de la maquinaria de construcci\u00f3n y miner\u00eda, que estamos seguros se convertir\u00e1 nuevamente en el punto de encuentro elegido por profesionales, fabricantes y distribuidores para mostrar sus \u00faltimos productos, desarrollos e innovaciones que transforman el sector.<\/p>\n\n\n\n<p>Os esperamos a todos en nuestro stand en el que os informaremos en detalle de todas las actividades que estamos organizando, as\u00ed como de otras sorpresas que os desvelaremos en vuestra visita.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp\" alt=\"\" class=\"wp-image-17002\" srcset=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp 1024w, https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC-300x180.webp 300w, https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC-768x461.webp 768w, https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC-18x12.webp 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Desde ANMOPYC estamos ultimando todos los detalles para la 20\u00aa edici\u00f3n de SMOPYC, que tendr\u00e1 lugar entre los pr\u00f3ximos 15 a 18 de abril en Feria de Zaragoza y que se convertir\u00e1 de nuevo en el punto de encuentro de nuestro sector en una edici\u00f3n que ha generado muchas expectativas y que contar\u00e1 con m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":17002,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[216],"tags":[],"class_list":["post-17000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-anmopyc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/fr\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad - Anmopyc\" \/>\n<meta property=\"og:description\" content=\"Desde ANMOPYC estamos ultimando todos los detalles para la 20\u00aa edici\u00f3n de SMOPYC, que tendr\u00e1 lugar entre los pr\u00f3ximos 15 a 18 de abril en Feria de Zaragoza y que se convertir\u00e1 de nuevo en el punto de encuentro de nuestro sector en una edici\u00f3n que ha generado muchas expectativas y que contar\u00e1 con m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/fr\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T07:04:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T07:05:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Javier Salvador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Salvador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\"},\"author\":{\"name\":\"Javier Salvador\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa\"},\"headline\":\"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad\",\"datePublished\":\"2026-03-24T07:04:15+00:00\",\"dateModified\":\"2026-03-24T07:05:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\"},\"wordCount\":1072,\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp\",\"articleSection\":[\"Noticias Anmopyc\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\",\"url\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\",\"name\":\"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp\",\"datePublished\":\"2026-03-24T07:04:15+00:00\",\"dateModified\":\"2026-03-24T07:05:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp\",\"width\":1024,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/anmopyc.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/anmopyc.es\/en\/#website\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/anmopyc.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anmopyc.red\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa\",\"name\":\"Javier Salvador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g\",\"caption\":\"Javier Salvador\"},\"url\":\"https:\/\/anmopyc.es\/fr\/author\/javier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/fr\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/","og_locale":"fr_FR","og_type":"article","og_title":"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad - Anmopyc","og_description":"Desde ANMOPYC estamos ultimando todos los detalles para la 20\u00aa edici\u00f3n de SMOPYC, que tendr\u00e1 lugar entre los pr\u00f3ximos 15 a 18 de abril en Feria de Zaragoza y que se convertir\u00e1 de nuevo en el punto de encuentro de nuestro sector en una edici\u00f3n que ha generado muchas expectativas y que contar\u00e1 con m\u00e1s [&hellip;]","og_url":"https:\/\/anmopyc.es\/fr\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","article_published_time":"2026-03-24T07:04:15+00:00","article_modified_time":"2026-03-24T07:05:17+00:00","og_image":[{"width":1024,"height":614,"url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp","type":"image\/webp"}],"author":"Javier Salvador","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Javier Salvador","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#article","isPartOf":{"@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/"},"author":{"name":"Javier Salvador","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa"},"headline":"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad","datePublished":"2026-03-24T07:04:15+00:00","dateModified":"2026-03-24T07:05:17+00:00","mainEntityOfPage":{"@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/"},"wordCount":1072,"publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"image":{"@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp","articleSection":["Noticias Anmopyc"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/","url":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/","name":"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp","datePublished":"2026-03-24T07:04:15+00:00","dateModified":"2026-03-24T07:05:17+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2026\/03\/Imagen-ANMOPYC-en-SMOPYC.webp","width":1024,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/anmopyc-llevara-a-smopyc-un-completo-programa-centrado-en-tecnologia-y-sostenibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/en\/"},{"@type":"ListItem","position":2,"name":"ANMOPYC llevar\u00e1 a SMOPYC un completo programa centrado en tecnolog\u00eda y sostenibilidad"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/en\/#website","url":"https:\/\/anmopyc.es\/en\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/en\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]},{"@type":"Person","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa","name":"Javier Salvador","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g","caption":"Javier Salvador"},"url":"https:\/\/anmopyc.es\/fr\/author\/javier\/"}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/17000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/comments?post=17000"}],"version-history":[{"count":2,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/17000\/revisions"}],"predecessor-version":[{"id":17003,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/17000\/revisions\/17003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/media\/17002"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/media?parent=17000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/categories?post=17000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/tags?post=17000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}