{"id":5796,"date":"2025-07-07T00:00:00","date_gmt":"2025-07-07T05:00:00","guid":{"rendered":""},"modified":"2025-12-11T17:00:24","modified_gmt":"2025-12-11T17:00:24","slug":"el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas","status":"publish","type":"post","link":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/","title":{"rendered":"Le pacte de comp\u00e9tences a form\u00e9 plus de 6 millions de personnes"},"content":{"rendered":"<p><a href=\"https:\/\/employment-social-affairs.ec.europa.eu\/policies-and-activities\/skills-and-qualifications\/working-together\/pact-skills_en?prefLang=es\" target=\"_blank\">El Pacto por las Competencias (Pact for Skills)<\/a>, se trata de una iniciativa esencial para equiparar las competencias profesionales en Europa, tambi\u00e9n en el sector de la construcci\u00f3n.<\/p>\n<p style=\"text-align: justify; \">Entre las m\u00e1s de 3.200 organizaciones que forman parte del Pacto, hay empresas, entidades sociales, proveedores de formaci\u00f3n, autoridades locales y servicios de empleo.&nbsp; Todos ellos identifican las necesidades de cualificaci\u00f3n en sus respectivos sectores y aplicar soluciones concretas a trav\u00e9s de asociaciones estrat\u00e9gicas.<\/p>\n<p>Dentro del sector de la construcci\u00f3n el proyecto \u2018Construction Blueprint\u2018,&nbsp; ha contribuido activamente a la iniciativa ya que ha promovido la formaci\u00f3n en eficiencia energ\u00e9tica, digitalizaci\u00f3n y econom\u00eda circular.<\/p>\n<p><span style=\"font-size: 1rem;\">Los logros en 2024, han tenido un impacto positivo como lo demuestran las cifras:&nbsp;<\/span><\/p>\n<ul>\n<li style=\"text-align: justify; \"><span style=\"font-size: 1rem;\">Cerca de 48.000 programas de formaci\u00f3n nuevos o actualizados.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"font-size: 1rem;\">M\u00e1s de 42.000 actores implicados en redes de colaboraci\u00f3n.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"font-size: 1rem;\">El 84\u202f% de los miembros considera el Pacto una iniciativa valiosa, sobre todo en t\u00e9rminos de colaboraci\u00f3n, acceso a financiaci\u00f3n y an\u00e1lisis de necesidades formativas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 1rem;\">Debido a los logros de esta primera fase, se ha lanzado<\/span><span style=\"font-size: 1rem;\">&nbsp;<\/span><span style=\"font-size: 1rem;\">\u2018Construction Blueprint 2\u2018 continuando con su compromiso de cualificar a los trabajadores del sector de la construcci\u00f3n.&nbsp;<\/span><\/p>\n<p style=\"text-align: center; \"><a href=\"https:\/\/constructionblueprint.eu\/es\/2025\/06\/10\/mas-de-61-millones-de-personas-formadas-desde-2020-gracias-al-pacto-por-las-competencias\/\" target=\"_blank\">Poursuivre la lecture<\/a><\/p>\n<p style=\"text-align: center; \">Source : <a href=\"https:\/\/www.fundacionlaboral.org\/\" target=\"_blank\">Fondation du travail de la construction<\/a><\/p>\n<p style=\"text-align: center; \"><\/p>","protected":false},"excerpt":{"rendered":"<p>El Pacto por las Competencias (Pact for Skills), se trata de una iniciativa esencial para equiparar las competencias profesionales en Europa, tambi\u00e9n en el sector de la construcci\u00f3n. Entre las m\u00e1s de 3.200 organizaciones que forman parte del Pacto, hay empresas, entidades sociales, proveedores de formaci\u00f3n, autoridades locales y servicios de empleo.&nbsp; Todos ellos identifican [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[218],"tags":[],"class_list":["post-5796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sector"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas - Anmopyc\" \/>\n<meta property=\"og:description\" content=\"El Pacto por las Competencias (Pact for Skills), se trata de una iniciativa esencial para equiparar las competencias profesionales en Europa, tambi\u00e9n en el sector de la construcci\u00f3n. Entre las m\u00e1s de 3.200 organizaciones que forman parte del Pacto, hay empresas, entidades sociales, proveedores de formaci\u00f3n, autoridades locales y servicios de empleo.&nbsp; Todos ellos identifican [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T17:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"claudia@wsiup.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudia@wsiup.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\"},\"author\":{\"name\":\"claudia@wsiup.com\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/person\/39699c208daead94ca4bc53387e71ce9\"},\"headline\":\"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas\",\"datePublished\":\"2025-07-07T05:00:00+00:00\",\"dateModified\":\"2025-12-11T17:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\"},\"wordCount\":229,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp\",\"articleSection\":[\"Sector\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\",\"url\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\",\"name\":\"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp\",\"datePublished\":\"2025-07-07T05:00:00+00:00\",\"dateModified\":\"2025-12-11T17:00:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp\",\"width\":950,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/anmopyc.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/anmopyc.es\/en\/#website\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/anmopyc.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anmopyc.red\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/person\/39699c208daead94ca4bc53387e71ce9\",\"name\":\"claudia@wsiup.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/bc6aeea3688a2635eb5f1d50f4ed08c6e633df003b030d05f21f405571741857?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc6aeea3688a2635eb5f1d50f4ed08c6e633df003b030d05f21f405571741857?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc6aeea3688a2635eb5f1d50f4ed08c6e633df003b030d05f21f405571741857?s=96&d=mm&r=g\",\"caption\":\"claudia@wsiup.com\"},\"sameAs\":[\"http:\/\/anmopyc.es\"],\"url\":\"https:\/\/anmopyc.es\/fr\/author\/claudiawsiup-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/","og_locale":"fr_FR","og_type":"article","og_title":"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas - Anmopyc","og_description":"El Pacto por las Competencias (Pact for Skills), se trata de una iniciativa esencial para equiparar las competencias profesionales en Europa, tambi\u00e9n en el sector de la construcci\u00f3n. Entre las m\u00e1s de 3.200 organizaciones que forman parte del Pacto, hay empresas, entidades sociales, proveedores de formaci\u00f3n, autoridades locales y servicios de empleo.&nbsp; Todos ellos identifican [&hellip;]","og_url":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","article_published_time":"2025-07-07T05:00:00+00:00","article_modified_time":"2025-12-11T17:00:24+00:00","og_image":[{"width":950,"height":534,"url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp","type":"image\/webp"}],"author":"claudia@wsiup.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"claudia@wsiup.com","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#article","isPartOf":{"@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/"},"author":{"name":"claudia@wsiup.com","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/person\/39699c208daead94ca4bc53387e71ce9"},"headline":"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas","datePublished":"2025-07-07T05:00:00+00:00","dateModified":"2025-12-11T17:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/"},"wordCount":229,"commentCount":0,"publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"image":{"@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp","articleSection":["Sector"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/","url":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/","name":"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp","datePublished":"2025-07-07T05:00:00+00:00","dateModified":"2025-12-11T17:00:24+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/07\/CONSTRUCTION-BLUEPRINT_w.webp","width":950,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/fr\/el-pacto-por-las-competencias-ha-formado-a-mas-de-6-millones-de-personas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/en\/"},{"@type":"ListItem","position":2,"name":"El Pacto por las Competencias ha formado a m\u00e1s de 6 millones de personas"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/en\/#website","url":"https:\/\/anmopyc.es\/en\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/en\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]},{"@type":"Person","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/person\/39699c208daead94ca4bc53387e71ce9","name":"claudia@wsiup.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bc6aeea3688a2635eb5f1d50f4ed08c6e633df003b030d05f21f405571741857?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc6aeea3688a2635eb5f1d50f4ed08c6e633df003b030d05f21f405571741857?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc6aeea3688a2635eb5f1d50f4ed08c6e633df003b030d05f21f405571741857?s=96&d=mm&r=g","caption":"claudia@wsiup.com"},"sameAs":["http:\/\/anmopyc.es"],"url":"https:\/\/anmopyc.es\/fr\/author\/claudiawsiup-com\/"}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/5796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/comments?post=5796"}],"version-history":[{"count":1,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/5796\/revisions"}],"predecessor-version":[{"id":9211,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/5796\/revisions\/9211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/media\/9926"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/media?parent=5796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/categories?post=5796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/tags?post=5796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}