{"id":5851,"date":"2025-11-20T00:00:00","date_gmt":"2025-11-20T05:00:00","guid":{"rendered":""},"modified":"2025-12-29T07:02:42","modified_gmt":"2025-12-29T07:02:42","slug":"cesce-country-risk-weekly-key-2","status":"publish","type":"post","link":"https:\/\/anmopyc.es\/fr\/cesce-riesgo-pais-claves-semanales-2\/","title":{"rendered":"Cesce : Faits marquants de la semaine sur le risque pays - 11-16 novembre 2025"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/adm.anmopyc.org\/uploads\/noticias\/18803\/BOLA_MUNDO_w.png\" alt=\"WORLD_BALL_w.png\" \/><span style=\"font-size: 1rem;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 1rem;\">Il passe en revue l'actualit\u00e9 \u00e9conomique et politique internationale.<\/span><\/p>\n<p><span style=\"font-size: 1rem;\">Dans le document ci-dessous, vous trouverez le suivi de l'actualit\u00e9 internationale compil\u00e9 par les experts analystes de <a href=\"https:\/\/www.cesce.es\/es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: bolder;\">Risque pays et gestion de la dette<\/span><\/a>\u00a0<\/span><a style=\"background-color: #ffffff; font-size: 1rem;\" href=\"https:\/\/www.cesce.es\/es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: bolder;\">de Cesce<\/span><\/a><span style=\"font-size: 1rem;\"> avec les cl\u00e9s de la semaine.<\/span><\/p>\n<p><a href=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Riesgo-Pais-Claves-de-la-semana-del-11-al-16-de-noviembre.pdf\">Risque pays - Faits marquants de la semaine du 11 au 16 novembre<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Faites le point sur l'actualit\u00e9 \u00e9conomique et politique internationale. Dans le document ci-dessous, vous trouverez le suivi de l'actualit\u00e9 internationale pr\u00e9par\u00e9 par les analystes experts en risque pays et en gestion de la dette du Cesce avec les principales nouvelles de la semaine. Risque pays - Les points cl\u00e9s de la semaine du 11 au 16 novembre<\/p>","protected":false},"author":8,"featured_media":5854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[212,214],"tags":[],"class_list":["post-5851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-cesce-riesgo-pais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cesce: Riesgo Pa\u00eds Claves Semanales - 11-16 noviembre 2025 - Anmopyc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anmopyc.es\/fr\/cesce-country-risk-weekly-key-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cesce: Riesgo Pa\u00eds Claves Semanales - 11-16 noviembre 2025 - Anmopyc\" \/>\n<meta property=\"og:description\" content=\"Repasa la actualidad econ\u00f3mica y pol\u00edtica internacional. En el documento inferior, encontrar\u00e1s el seguimiento de noticias internacionales elaborada por los expertos analistas de Riesgo Pa\u00eds y Gesti\u00f3n de Deuda\u00a0de Cesce con las claves de la semana. Riesgo Pa\u00eds &#8211; Claves de la semana del 11 al 16 de noviembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anmopyc.es\/fr\/cesce-country-risk-weekly-key-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Anmopyc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anmopyc.red\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T07:02:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"606\" \/>\n\t<meta property=\"og:image:height\" content=\"855\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Javier Salvador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Salvador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/\"},\"author\":{\"name\":\"Javier Salvador\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa\"},\"headline\":\"Cesce: Riesgo Pa\u00eds Claves Semanales &#8211; 11-16 noviembre 2025\",\"datePublished\":\"2025-11-20T05:00:00+00:00\",\"dateModified\":\"2025-12-29T07:02:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/\"},\"wordCount\":63,\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp\",\"articleSection\":[\"Agenda\",\"Cesce Riesgo Pa\u00eds\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/\",\"url\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/\",\"name\":\"Cesce: Riesgo Pa\u00eds Claves Semanales - 11-16 noviembre 2025 - Anmopyc\",\"isPartOf\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp\",\"datePublished\":\"2025-11-20T05:00:00+00:00\",\"dateModified\":\"2025-12-29T07:02:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp\",\"width\":606,\"height\":855},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/anmopyc.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cesce: Riesgo Pa\u00eds Claves Semanales &#8211; 11-16 noviembre 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/anmopyc.es\/en\/#website\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"name\":\"Anmopyc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/anmopyc.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/anmopyc.es\/en\/#organization\",\"name\":\"Anmopyc\",\"url\":\"https:\/\/anmopyc.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"contentUrl\":\"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg\",\"width\":372,\"height\":129,\"caption\":\"Anmopyc\"},\"image\":{\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/anmopyc.red\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa\",\"name\":\"Javier Salvador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g\",\"caption\":\"Javier Salvador\"},\"url\":\"https:\/\/anmopyc.es\/fr\/author\/javier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cesce : Faits marquants de la semaine sur le risque pays - 11-16 novembre 2025 - Anmopyc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anmopyc.es\/fr\/cesce-country-risk-weekly-key-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Cesce: Riesgo Pa\u00eds Claves Semanales - 11-16 noviembre 2025 - Anmopyc","og_description":"Repasa la actualidad econ\u00f3mica y pol\u00edtica internacional. En el documento inferior, encontrar\u00e1s el seguimiento de noticias internacionales elaborada por los expertos analistas de Riesgo Pa\u00eds y Gesti\u00f3n de Deuda\u00a0de Cesce con las claves de la semana. Riesgo Pa\u00eds &#8211; Claves de la semana del 11 al 16 de noviembre","og_url":"https:\/\/anmopyc.es\/fr\/cesce-country-risk-weekly-key-2\/","og_site_name":"Anmopyc","article_publisher":"https:\/\/www.facebook.com\/anmopyc.red","article_published_time":"2025-11-20T05:00:00+00:00","article_modified_time":"2025-12-29T07:02:42+00:00","og_image":[{"width":606,"height":855,"url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp","type":"image\/webp"}],"author":"Javier Salvador","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Javier Salvador","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#article","isPartOf":{"@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/"},"author":{"name":"Javier Salvador","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa"},"headline":"Cesce: Riesgo Pa\u00eds Claves Semanales &#8211; 11-16 noviembre 2025","datePublished":"2025-11-20T05:00:00+00:00","dateModified":"2025-12-29T07:02:42+00:00","mainEntityOfPage":{"@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/"},"wordCount":63,"publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"image":{"@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp","articleSection":["Agenda","Cesce Riesgo Pa\u00eds"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/","url":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/","name":"Cesce : Faits marquants de la semaine sur le risque pays - 11-16 novembre 2025 - Anmopyc","isPartOf":{"@id":"https:\/\/anmopyc.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage"},"image":{"@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage"},"thumbnailUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp","datePublished":"2025-11-20T05:00:00+00:00","dateModified":"2025-12-29T07:02:42+00:00","breadcrumb":{"@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#primaryimage","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/11\/Cesce-11-16-noviembre.webp","width":606,"height":855},{"@type":"BreadcrumbList","@id":"https:\/\/anmopyc.es\/en\/cesce-riesgo-pais-claves-semanales-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anmopyc.es\/en\/"},{"@type":"ListItem","position":2,"name":"Cesce: Riesgo Pa\u00eds Claves Semanales &#8211; 11-16 noviembre 2025"}]},{"@type":"WebSite","@id":"https:\/\/anmopyc.es\/en\/#website","url":"https:\/\/anmopyc.es\/en\/","name":"Anmopyc","description":"","publisher":{"@id":"https:\/\/anmopyc.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anmopyc.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/anmopyc.es\/en\/#organization","name":"Anmopyc","url":"https:\/\/anmopyc.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","contentUrl":"https:\/\/anmopyc.es\/wp-content\/uploads\/2025\/10\/anmopyc-correctoAZUL.svg","width":372,"height":129,"caption":"Anmopyc"},"image":{"@id":"https:\/\/anmopyc.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anmopyc.red"]},{"@type":"Person","@id":"https:\/\/anmopyc.es\/en\/#\/schema\/person\/63199c82e98f713d9bd8f20ebfdde1fa","name":"Javier Salvador","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3c3184ded44a29cc36d4759b237965eb65544eb3a8aef1489480fe1b148bbbb?s=96&d=mm&r=g","caption":"Javier Salvador"},"url":"https:\/\/anmopyc.es\/fr\/author\/javier\/"}]}},"_links":{"self":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/5851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/comments?post=5851"}],"version-history":[{"count":4,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/5851\/revisions"}],"predecessor-version":[{"id":13905,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/posts\/5851\/revisions\/13905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/media\/5854"}],"wp:attachment":[{"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/media?parent=5851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/categories?post=5851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anmopyc.es\/fr\/wp-json\/wp\/v2\/tags?post=5851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}